{"id":8058,"date":"2024-04-09T16:50:12","date_gmt":"2024-04-09T08:50:12","guid":{"rendered":"https:\/\/plasticmachinesl.com\/?p=8058"},"modified":"2024-04-09T17:04:54","modified_gmt":"2024-04-09T09:04:54","slug":"plastic-scrap-shredder-machine-shipment","status":"publish","type":"post","link":"https:\/\/plasticmachinesl.com\/pt\/plastic-scrap-shredder-machine-shipment\/","title":{"rendered":"M\u00e1quina trituradora de sucata de pl\u00e1stico enviada para a Tanz\u00e2nia"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Recentemente, recebemos uma consulta de um cliente da Tanz\u00e2nia que precisava de uma m\u00e1quina trituradora de sucata de pl\u00e1stico para processar tambores de pl\u00e1stico e garrafas PET. Atrav\u00e9s da comunica\u00e7\u00e3o detalhada entre o nosso gestor de vendas Hailey e o cliente, compreendemos as necessidades do cliente e fornecemos-lhe uma solu\u00e7\u00e3o adequada.<\/p>    <h2 class=\"wp-block-heading\">Solu\u00e7\u00f5es e produ\u00e7\u00e3o recomendadas<\/h2>    <p class=\"wp-block-paragraph\">Depois de confirmar cuidadosamente as necessidades do cliente, nosso gerente de vendas Hailey recomendou nossas 800 m\u00e1quinas trituradoras de sucata de pl\u00e1stico para servi\u00e7os pesados, que podem atender \u00e0s necessidades do cliente para triturar tambores pl\u00e1sticos e garrafas PET. O cliente ficou satisfeito com a nossa recomenda\u00e7\u00e3o e o pedido foi rapidamente finalizado.<\/p>    <p class=\"wp-block-paragraph\">Nossa equipe de produ\u00e7\u00e3o come\u00e7ou imediatamente a trabalhar neste modelo espec\u00edfico de trituradora. Ap\u00f3s cuidadosa montagem e teste, a m\u00e1quina passou na inspe\u00e7\u00e3o de qualidade e estava pronta para ser enviada para a Tanz\u00e2nia.<\/p>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"8065\" src=\"https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/Plastic-Crusher-Sent-to-Tanzania.webp\" alt=\"Triturador de pl\u00e1stico enviado para a Tanz\u00e2nia\" class=\"wp-image-8065\" srcset=\"https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/Plastic-Crusher-Sent-to-Tanzania.webp 720w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/Plastic-Crusher-Sent-to-Tanzania-360x270.webp 360w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/Plastic-Crusher-Sent-to-Tanzania-240x180.webp 240w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/Plastic-Crusher-Sent-to-Tanzania-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">Triturador de pl\u00e1stico enviado para a Tanz\u00e2nia<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"8066\" src=\"https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/plastic-recycling-shredder-machine-shipment.webp\" alt=\"remessa de m\u00e1quina trituradora de reciclagem de pl\u00e1stico\" class=\"wp-image-8066\" srcset=\"https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/plastic-recycling-shredder-machine-shipment.webp 720w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/plastic-recycling-shredder-machine-shipment-360x270.webp 360w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/plastic-recycling-shredder-machine-shipment-240x180.webp 240w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/plastic-recycling-shredder-machine-shipment-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">remessa de m\u00e1quina trituradora de reciclagem de pl\u00e1stico<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\">Par\u00e2metros da m\u00e1quina trituradora de sucata de pl\u00e1stico<\/h2>    <div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/plastic-waste-crushing-machine.webp\" alt=\"\" class=\"wp-image-8068 size-full\" srcset=\"https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/plastic-waste-crushing-machine.webp 720w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/plastic-waste-crushing-machine-360x270.webp 360w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/plastic-waste-crushing-machine-240x180.webp 240w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/plastic-waste-crushing-machine-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure><div class=\"wp-block-media-text__content\"> <ul class=\"wp-block-list\"> <li>Modelo: 800 pesado<\/li>    <li>Espessura da placa da caixa: 30mm<\/li>    <li>Espessura fixa do porta-faca: 50mm<\/li>    <li>Pot\u00eancia: 45KW, redutor ZQ200<\/li>    <li>Tamanho da m\u00e1quina: 1450*<em>2600<\/em>*2100mm<\/li> <\/ul> <\/div><\/div>    <p class=\"wp-block-paragraph translation-block\">Envi\u00e1mos a <strong><a href=\"https:\/\/plasticmachinesl.com\/pt\/plastic-shredder-machine\/\">m\u00e1quina trituradora de res\u00edduos pl\u00e1sticos<\/a><\/strong> para a Tanz\u00e2nia e aguardamos com expectativa o feedback satisfat\u00f3rio dos clientes ap\u00f3s a rece\u00e7\u00e3o do equipamento. Como empresa dedicada a fornecer solu\u00e7\u00f5es \u00f3timas aos nossos clientes, continuaremos a trabalhar arduamente para manter produtos de elevada qualidade e um servi\u00e7o excelente, bem como para fornecer apoio e assist\u00eancia abrangentes aos nossos clientes.<\/p>","protected":false},"excerpt":{"rendered":"<p>Recentemente recebemos uma consulta de um cliente da Tanz\u00e2nia que precisava de sucata de pl\u00e1stico\u2026<\/p>","protected":false},"author":1,"featured_media":8059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[9],"tags":[],"class_list":["post-8058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cases"],"taxonomy_info":{"category":[{"value":9,"label":"Cases"}]},"featured_image_src_large":["https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2024\/04\/plastic-scrap-shredder-machine.webp",720,540,false],"author_info":{"display_name":"Elena","author_link":"https:\/\/plasticmachinesl.com\/pt\/author\/adminelena\/"},"comment_info":0,"category_info":[{"term_id":9,"name":"Cases","slug":"cases","term_group":0,"term_taxonomy_id":9,"taxonomy":"category","description":"","parent":0,"count":68,"filter":"raw","cat_ID":9,"category_count":68,"category_description":"","cat_name":"Cases","category_nicename":"cases","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/plasticmachinesl.com\/pt\/wp-json\/wp\/v2\/posts\/8058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plasticmachinesl.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plasticmachinesl.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plasticmachinesl.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plasticmachinesl.com\/pt\/wp-json\/wp\/v2\/comments?post=8058"}],"version-history":[{"count":0,"href":"https:\/\/plasticmachinesl.com\/pt\/wp-json\/wp\/v2\/posts\/8058\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plasticmachinesl.com\/pt\/wp-json\/wp\/v2\/media\/8059"}],"wp:attachment":[{"href":"https:\/\/plasticmachinesl.com\/pt\/wp-json\/wp\/v2\/media?parent=8058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plasticmachinesl.com\/pt\/wp-json\/wp\/v2\/categories?post=8058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plasticmachinesl.com\/pt\/wp-json\/wp\/v2\/tags?post=8058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}