{"id":4323,"date":"2023-11-14T16:34:45","date_gmt":"2023-11-14T08:34:45","guid":{"rendered":"https:\/\/plasticmachinesl.com\/?p=4323"},"modified":"2023-11-14T17:20:28","modified_gmt":"2023-11-14T09:20:28","slug":"hard-plastic-crusher-sent-to-somalia","status":"publish","type":"post","link":"https:\/\/plasticmachinesl.com\/fr\/hard-plastic-crusher-sent-to-somalia\/","title":{"rendered":"Concasseur de plastique dur SL-800 envoy\u00e9 en Somalie"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Ce client de Somalie a choisi notre broyeur en plastique dur. Il va utiliser la machine pour broyer des d\u00e9chets plastiques durs. Nous recommandons au client le broyeur de plastique rigide mod\u00e8le SL-800, sp\u00e9cialement con\u00e7u pour broyer les plastiques durs, avec une capacit\u00e9 de 700 \u00e0 800 kg\/h, ce qui peut r\u00e9pondre pleinement aux besoins des clients somaliens.<\/p>    <h2 class=\"wp-block-heading\">param\u00e8tres du broyeur de plastique dur en somalie<\/h2>    <p class=\"wp-block-paragraph\">La d\u00e9chiqueteuse de plastique rigide mod\u00e8le SL-800 est une machine efficace et puissante, propuls\u00e9e par un moteur diesel de 35 ch pour assurer une forte puissance de sortie. Avec son excellente capacit\u00e9 allant jusqu'\u00e0 700 \u00e0 800 kg par heure, elle convient au traitement de grandes quantit\u00e9s de d\u00e9chets plastiques durs. \u00c9quip\u00e9 de lames robustes de 400 mm de long, 100 mm de large et 16 mm d'\u00e9paisseur, le broyeur cisaille, d\u00e9chire et \u00e9crase efficacement les plastiques durs, fournissant ainsi la mati\u00e8re premi\u00e8re id\u00e9ale pour les processus de recyclage ult\u00e9rieurs.<\/p>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"4329\" src=\"https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2023\/11\/hard-plastic-crusher.webp\" alt=\"concasseur en plastique dur\" class=\"wp-image-4329\" srcset=\"https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2023\/11\/hard-plastic-crusher.webp 720w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2023\/11\/hard-plastic-crusher-360x270.webp 360w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2023\/11\/hard-plastic-crusher-240x180.webp 240w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">concasseur en plastique dur<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"4330\" src=\"https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2023\/11\/hard-plastic-shredder.webp\" alt=\"broyeur en plastique dur\" class=\"wp-image-4330\" srcset=\"https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2023\/11\/hard-plastic-shredder.webp 720w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2023\/11\/hard-plastic-shredder-360x270.webp 360w, https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2023\/11\/hard-plastic-shredder-240x180.webp 240w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">broyeur en plastique dur<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\">Les clients ont visit\u00e9 notre usine<\/h2>    <p class=\"wp-block-paragraph translation-block\">Apr\u00e8s la production de l'\u00e9quipement a \u00e9t\u00e9 achev\u00e9e, les clients somaliens sont venus dans notre usine en personne et ont proc\u00e9d\u00e9 \u00e0 une inspection compl\u00e8te du produit du <strong><a href=\"https:\/\/plasticmachinesl.com\/fr\/plastic-shredder-machine\/\" data-type=\"link\" data-id=\"https:\/\/plasticmachinesl.com\/plastic-shredder-machine\/\">grossier broyeur de plastique dur<\/a><\/strong> SL-800. Gr\u00e2ce \u00e0 une observation et une inspection d\u00e9taill\u00e9es, le client a parfaitement compris les performances de la machine en termes de conditions de travail et d'effets. Apr\u00e8s des tests rigoureux, le client a fait l'\u00e9loge de nos produits et a exprim\u00e9 une grande satisfaction quant au fonctionnement stable de la machine et \u00e0 son excellente performance dans le traitement efficace des plastiques difficiles. Ce qui suit est la vid\u00e9o du site d'inspection du client.<\/p>    <figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"> <iframe loading=\"lazy\" title=\"Machine de d\u00e9chiquetage de plastique rigide au travail\u00a0: \u00e9craser les d\u00e9chets de plastique en petits morceaux\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/a83BFKULCFo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe> <\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Ce client de Somalie a choisi notre broyeur en plastique dur. Il va utiliser le\u2026<\/p>","protected":false},"author":1,"featured_media":3536,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[9],"tags":[],"class_list":["post-4323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cases"],"taxonomy_info":{"category":[{"value":9,"label":"Cases"}]},"featured_image_src_large":["https:\/\/plasticmachinesl.com\/wp-content\/uploads\/2023\/10\/rigid-plastic-shredder-machine.webp",720,540,false],"author_info":{"display_name":"Elena","author_link":"https:\/\/plasticmachinesl.com\/fr\/author\/adminelena\/"},"comment_info":1,"category_info":[{"term_id":9,"name":"Cases","slug":"cases","term_group":0,"term_taxonomy_id":9,"taxonomy":"category","description":"","parent":0,"count":68,"filter":"raw","cat_ID":9,"category_count":68,"category_description":"","cat_name":"Cases","category_nicename":"cases","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/plasticmachinesl.com\/fr\/wp-json\/wp\/v2\/posts\/4323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plasticmachinesl.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plasticmachinesl.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plasticmachinesl.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plasticmachinesl.com\/fr\/wp-json\/wp\/v2\/comments?post=4323"}],"version-history":[{"count":0,"href":"https:\/\/plasticmachinesl.com\/fr\/wp-json\/wp\/v2\/posts\/4323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plasticmachinesl.com\/fr\/wp-json\/wp\/v2\/media\/3536"}],"wp:attachment":[{"href":"https:\/\/plasticmachinesl.com\/fr\/wp-json\/wp\/v2\/media?parent=4323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plasticmachinesl.com\/fr\/wp-json\/wp\/v2\/categories?post=4323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plasticmachinesl.com\/fr\/wp-json\/wp\/v2\/tags?post=4323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}